{"id":26071,"date":"2023-08-09T16:20:43","date_gmt":"2023-08-09T16:20:43","guid":{"rendered":"https:\/\/ozeyhome.com\/product\/%d8%b4%d9%8a%d9%83%d9%88-%d9%81%d8%b1%d8%b4%d8%a7%d8%a9-%d9%88%d9%85%d8%b4%d8%b7-%d8%a8%d8%b1%d8%aa%d9%82%d8%a7%d9%84%d9%8a\/"},"modified":"2026-06-20T09:39:37","modified_gmt":"2026-06-20T09:39:37","slug":"%d8%b4%d9%8a%d9%83%d9%88-%d9%81%d8%b1%d8%b4%d8%a7%d8%a9-%d9%88%d9%85%d8%b4%d8%b7-%d8%a8%d8%b1%d8%aa%d9%82%d8%a7%d9%84%d9%8a","status":"publish","type":"product","link":"https:\/\/ozeyhome.com\/ar\/product\/%d8%b4%d9%8a%d9%83%d9%88-%d9%81%d8%b1%d8%b4%d8%a7%d8%a9-%d9%88%d9%85%d8%b4%d8%b7-%d8%a8%d8%b1%d8%aa%d9%82%d8%a7%d9%84%d9%8a\/","title":{"rendered":"\u0641\u0631\u0634\u0627\u0629 \u0648\u0645\u0634\u0637 \u0628\u0631\u062a\u0642\u0627\u0644\u064a &#8211; \u062a\u0634\u064a\u0643\u0648"},"content":{"rendered":"<p>\u0645\u0648\u0635\u0649 \u0628\u0647 \u0644\u0644\u0623\u0637\u0641\u0627\u0644 0M +. \u062a\u0639\u062a\u0628\u0631 \u0641\u0631\u0634\u0627\u0629 \u0648\u0645\u0634\u0637 \u0634\u064a\u0643\u0648 \u0645\u062b\u0627\u0644\u064a\u064a\u0646 \u0644\u062a\u0645\u0634\u064a\u0637 \u0634\u0639\u0631 \u0627\u0644\u0637\u0641\u0644 \u0628\u0623\u0642\u0635\u0649 \u062f\u0631\u062c\u0627\u062a \u0627\u0644\u062d\u0633\u0627\u0633\u064a\u0629. \u0647\u0630\u0647 \u0644\u0627 \u062a\u0624\u0630\u064a \u0627\u0644\u0637\u0641\u0644 \u0648\u0647\u064a \u0646\u0627\u0639\u0645\u0629 \u0644\u0634\u0639\u0631\u0647 \u0627\u0644\u0631\u0642\u064a\u0642 \u0648\u0641\u0631\u0648\u0629 \u0631\u0623\u0633\u0647.<\/p>\n<p class=\"text_green\">\u0627\u0644\u0639\u0645\u0631 \u0627\u0644\u0645\u0646\u0627\u0633\u0628: 0 \u0634\u0647\u0631 +<\/p>\n<div class=\"row product_features mt-lg-5 mt-3\">\n<div class=\"col-md-12\">\n<h2>\u0633\u0645\u0627\u062a<\/h2>\n<div class=\"products_slider mt-4 pb-0\">\n<div class=\"owl-carousel owl-theme owl-loaded owl-drag\">\n<div class=\"owl-stage-outer\">\n<div class=\"owl-stage\">\n<div class=\"owl-item cloned\">\n<div class=\"item\">\n<div class=\"feature_box\">\n<h3>\u0645\u0642\u0628\u0636 \u063a\u064a\u0631 \u0642\u0627\u0628\u0644 \u0644\u0644\u0627\u0646\u0632\u0644\u0627\u0642<\/h3>\n<p>\u0645\u0642\u0628\u0636 \u0639\u0631\u064a\u0636 \u0648\u063a\u064a\u0631 \u0642\u0627\u0628\u0644 \u0644\u0644\u0627\u0646\u0632\u0644\u0627\u0642 \u064a\u0633\u0645\u062d \u0628\u0642\u0628\u0636\u0629 \u0633\u0647\u0644\u0629 \u0648\u0622\u0645\u0646\u0629.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"owl-item cloned\">\n<div class=\"item\">\n<div class=\"feature_box\">\n<h3>\u0641\u0631\u0634\u0627\u0629 \u0628\u0634\u0639\u064a\u0631\u0627\u062a \u0637\u0628\u064a\u0639\u064a\u0629<\/h3>\n<p>\u062a\u062d\u062a\u0631\u0645 \u0627\u0644\u0634\u0639\u064a\u0631\u0627\u062a \u0627\u0644\u0637\u0628\u064a\u0639\u064a\u0629 \u0627\u0644\u0646\u0627\u0639\u0645\u0629 \u0644\u0641\u0631\u0634\u0627\u0629 \u0627\u0644\u0634\u0639\u0631 \u0634\u064a\u0643\u0648 \u0641\u0631\u0648\u0629 \u0631\u0623\u0633 \u0627\u0644\u0637\u0641\u0644 \u0627\u0644\u062d\u0633\u0627\u0633\u0629 \u0623\u062b\u0646\u0627\u0621 \u0627\u0644\u062a\u0645\u0634\u064a\u0637.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"owl-item cloned\">\n<div class=\"item\">\n<div class=\"feature_box\">\n<h3>\u0645\u0634\u0637 \u0645\u0639 \u0646\u0635\u0627\u0626\u062d \u0645\u062f\u0648\u0631\u0629<\/h3>\n<p>\u0645\u0635\u0645\u0645 \u0644\u062a\u0645\u0634\u064a\u0637 \u0634\u0639\u0631 \u0627\u0644\u0637\u0641\u0644 \u0627\u0644\u0623\u0648\u0644 \u062f\u0648\u0646 \u062e\u062f\u0634 \u0628\u0634\u0631\u062a\u0647 \u0627\u0644\u0646\u0627\u0639\u0645\u0629.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"owl-item cloned\">\n<div class=\"item\">\n<div class=\"feature_box\"><\/div>\n<\/div>\n<\/div>\n<div class=\"owl-item cloned\">\n<div class=\"item\">\n<div class=\"feature_box\">\n<p>\u0641\u064a \u062d\u0627\u0644\u0629 \u0627\u0644\u0623\u0637\u0641\u0627\u0644 \u062d\u062f\u064a\u062b\u064a \u0627\u0644\u0648\u0644\u0627\u062f\u0629 \u060c \u064a\u0646\u0635\u062d \u062f\u0627\u0626\u0645\u0627 \u0628\u0627\u0633\u062a\u062e\u062f\u0627\u0645 \u0641\u0631\u0634\u0627\u0629 \u0644\u0634\u0639\u0631 \u0627\u0644\u0637\u0641\u0644 \u0627\u0644\u0631\u0642\u064a\u0642 \u0648\u0641\u0631\u0648\u0629 \u0631\u0623\u0633\u0647. \u0641\u0631\u0634\u0627\u0629 \u0634\u064a\u0643\u0648 \u0644\u0644\u0634\u0639\u0631 \u0644\u0644\u0623\u0637\u0641\u0627\u0644 \u0645\u0635\u0646\u0648\u0639\u0629 \u0645\u0646 \u0634\u0639\u064a\u0631\u0627\u062a \u0637\u0628\u064a\u0639\u064a\u0629 \u0646\u0627\u0639\u0645\u0629 \u062c\u062f\u0627 \u062a\u0639\u062a\u0646\u064a \u0628\u0627\u0644\u0628\u0634\u0631\u0629 \u0627\u0644\u062d\u0633\u0627\u0633\u0629 \u0644\u0641\u0631\u0648\u0629 \u0631\u0623\u0633 \u0627\u0644\u0637\u0641\u0644 \u0648\u062a\u0633\u0645\u062d \u0628\u062a\u0645\u0634\u064a\u0637 \u0634\u0639\u0631 \u0627\u0644\u0637\u0641\u0644 \u0628\u0644\u0637\u0641. \u064a\u062d\u062a\u0648\u064a \u0645\u0634\u0637 \u0634\u064a\u0643\u0648 \u0628\u064a\u0628\u064a \u0639\u0644\u0649 \u0623\u0633\u0646\u0627\u0646 \u0630\u0627\u062a \u0646\u0647\u0627\u064a\u0627\u062a \u0645\u0633\u062a\u062f\u064a\u0631\u0629 \u0645\u062b\u0627\u0644\u064a\u0629 \u0644\u0641\u0631\u0648\u0629 \u0631\u0623\u0633 \u0627\u0644\u0637\u0641\u0644 \u0627\u0644\u0635\u063a\u064a\u0631 \u0644\u0623\u0646\u0647\u0627 \u0645\u0635\u0645\u0645\u0629 \u0644\u062a\u0645\u0634\u064a\u0637 \u0634\u0639\u0631 \u0627\u0644\u0637\u0641\u0644 \u0627\u0644\u0623\u0648\u0644 \u062f\u0648\u0646 \u062e\u062f\u0634 \u0628\u0634\u0631\u062a\u0647 \u0627\u0644\u0646\u0627\u0639\u0645\u0629.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u0645\u0648\u0635\u0649 \u0628\u0647 \u0644\u0644\u0623\u0637\u0641\u0627\u0644 0M +. \u062a\u0639\u062a\u0628\u0631 \u0641\u0631\u0634\u0627\u0629 \u0648\u0645\u0634\u0637 \u0634\u064a\u0643\u0648 \u0645\u062b\u0627\u0644\u064a\u064a\u0646 \u0644\u062a\u0645\u0634\u064a\u0637 \u0634\u0639\u0631 \u0627\u0644\u0637\u0641\u0644 \u0628\u0623\u0642\u0635\u0649 \u062f\u0631\u062c\u0627\u062a \u0627\u0644\u062d\u0633\u0627\u0633\u064a\u0629. \u0647\u0630\u0647 \u0644\u0627 \u062a\u0624\u0630\u064a \u0627\u0644\u0637\u0641\u0644 \u0648\u0647\u064a \u0646\u0627\u0639\u0645\u0629 \u0644\u0634\u0639\u0631\u0647 \u0627\u0644\u0631\u0642\u064a\u0642 \u0648\u0641\u0631\u0648\u0629 \u0631\u0623\u0633\u0647. \u0627\u0644\u0639\u0645\u0631 \u0627\u0644\u0645\u0646\u0627\u0633\u0628: 0 \u0634\u0647\u0631 + \u0633\u0645\u0627\u062a \u0645\u0642\u0628\u0636 \u063a\u064a\u0631 \u0642\u0627\u0628\u0644 \u0644\u0644\u0627\u0646\u0632\u0644\u0627\u0642 \u0645\u0642\u0628\u0636 \u0639\u0631\u064a\u0636 \u0648\u063a\u064a\u0631 \u0642\u0627\u0628\u0644 \u0644\u0644\u0627\u0646\u0632\u0644\u0627\u0642 \u064a\u0633\u0645\u062d \u0628\u0642\u0628\u0636\u0629 \u0633\u0647\u0644\u0629 \u0648\u0622\u0645\u0646\u0629. \u0641\u0631\u0634\u0627\u0629 \u0628\u0634\u0639\u064a\u0631\u0627\u062a \u0637\u0628\u064a\u0639\u064a\u0629 \u062a\u062d\u062a\u0631\u0645 \u0627\u0644\u0634\u0639\u064a\u0631\u0627\u062a \u0627\u0644\u0637\u0628\u064a\u0639\u064a\u0629 \u0627\u0644\u0646\u0627\u0639\u0645\u0629 \u0644\u0641\u0631\u0634\u0627\u0629 \u0627\u0644\u0634\u0639\u0631 \u0634\u064a\u0643\u0648 &hellip; <a href=\"https:\/\/ozeyhome.com\/ar\/product\/%d8%b4%d9%8a%d9%83%d9%88-%d9%81%d8%b1%d8%b4%d8%a7%d8%a9-%d9%88%d9%85%d8%b4%d8%b7-%d8%a8%d8%b1%d8%aa%d9%82%d8%a7%d9%84%d9%8a\/\" class=\"more-link\">Continue reading <span class=\"screen-reader-text\">\u0641\u0631\u0634\u0627\u0629 \u0648\u0645\u0634\u0637 \u0628\u0631\u062a\u0642\u0627\u0644\u064a &#8211; \u062a\u0634\u064a\u0643\u0648<\/span><\/a><\/p>\n","protected":false},"featured_media":25717,"template":"","meta":{"_monsterinsights_skip_tracking":false},"product_brand":[],"product_cat":[925,538,944],"product_tag":[],"class_list":["post-26071","product","type-product","status-publish","has-post-thumbnail","product_cat-925","product_cat-538","product_cat-944","pa_brands-483","pa_color-419","instock","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u0641\u0631\u0634\u0627\u0629 \u0648\u0645\u0634\u0637 \u0628\u0631\u062a\u0642\u0627\u0644\u064a - \u062a\u0634\u064a\u0643\u0648 - Ozey Home<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ozeyhome.com\/ar\/product\/%d8%b4%d9%8a%d9%83%d9%88-%d9%81%d8%b1%d8%b4%d8%a7%d8%a9-%d9%88%d9%85%d8%b4%d8%b7-%d8%a8%d8%b1%d8%aa%d9%82%d8%a7%d9%84%d9%8a\/\" \/>\n<meta property=\"og:locale\" content=\"ar_AR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0641\u0631\u0634\u0627\u0629 \u0648\u0645\u0634\u0637 \u0628\u0631\u062a\u0642\u0627\u0644\u064a - \u062a\u0634\u064a\u0643\u0648 - Ozey Home\" \/>\n<meta property=\"og:description\" content=\"\u0645\u0648\u0635\u0649 \u0628\u0647 \u0644\u0644\u0623\u0637\u0641\u0627\u0644 0M +. \u062a\u0639\u062a\u0628\u0631 \u0641\u0631\u0634\u0627\u0629 \u0648\u0645\u0634\u0637 \u0634\u064a\u0643\u0648 \u0645\u062b\u0627\u0644\u064a\u064a\u0646 \u0644\u062a\u0645\u0634\u064a\u0637 \u0634\u0639\u0631 \u0627\u0644\u0637\u0641\u0644 \u0628\u0623\u0642\u0635\u0649 \u062f\u0631\u062c\u0627\u062a \u0627\u0644\u062d\u0633\u0627\u0633\u064a\u0629. \u0647\u0630\u0647 \u0644\u0627 \u062a\u0624\u0630\u064a \u0627\u0644\u0637\u0641\u0644 \u0648\u0647\u064a \u0646\u0627\u0639\u0645\u0629 \u0644\u0634\u0639\u0631\u0647 \u0627\u0644\u0631\u0642\u064a\u0642 \u0648\u0641\u0631\u0648\u0629 \u0631\u0623\u0633\u0647. \u0627\u0644\u0639\u0645\u0631 \u0627\u0644\u0645\u0646\u0627\u0633\u0628: 0 \u0634\u0647\u0631 + \u0633\u0645\u0627\u062a \u0645\u0642\u0628\u0636 \u063a\u064a\u0631 \u0642\u0627\u0628\u0644 \u0644\u0644\u0627\u0646\u0632\u0644\u0627\u0642 \u0645\u0642\u0628\u0636 \u0639\u0631\u064a\u0636 \u0648\u063a\u064a\u0631 \u0642\u0627\u0628\u0644 \u0644\u0644\u0627\u0646\u0632\u0644\u0627\u0642 \u064a\u0633\u0645\u062d \u0628\u0642\u0628\u0636\u0629 \u0633\u0647\u0644\u0629 \u0648\u0622\u0645\u0646\u0629. \u0641\u0631\u0634\u0627\u0629 \u0628\u0634\u0639\u064a\u0631\u0627\u062a \u0637\u0628\u064a\u0639\u064a\u0629 \u062a\u062d\u062a\u0631\u0645 \u0627\u0644\u0634\u0639\u064a\u0631\u0627\u062a \u0627\u0644\u0637\u0628\u064a\u0639\u064a\u0629 \u0627\u0644\u0646\u0627\u0639\u0645\u0629 \u0644\u0641\u0631\u0634\u0627\u0629 \u0627\u0644\u0634\u0639\u0631 \u0634\u064a\u0643\u0648 &hellip; Continue reading \u0641\u0631\u0634\u0627\u0629 \u0648\u0645\u0634\u0637 \u0628\u0631\u062a\u0642\u0627\u0644\u064a &#8211; \u062a\u0634\u064a\u0643\u0648\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ozeyhome.com\/ar\/product\/%d8%b4%d9%8a%d9%83%d9%88-%d9%81%d8%b1%d8%b4%d8%a7%d8%a9-%d9%88%d9%85%d8%b4%d8%b7-%d8%a8%d8%b1%d8%aa%d9%82%d8%a7%d9%84%d9%8a\/\" \/>\n<meta property=\"og:site_name\" content=\"Ozey Home\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-20T09:39:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ozeyhome.com\/wp-content\/uploads\/2023\/08\/o3.png\" \/>\n\t<meta property=\"og:image:width\" content=\"850\" \/>\n\t<meta property=\"og:image:height\" content=\"850\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u0648\u0642\u062a \u0627\u0644\u0642\u0631\u0627\u0621\u0629 \u0627\u0644\u0645\u064f\u0642\u062f\u0651\u0631\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u062f\u0642\u064a\u0642\u062a\u0627\u0646\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ozeyhome.com\\\/ar\\\/product\\\/%d8%b4%d9%8a%d9%83%d9%88-%d9%81%d8%b1%d8%b4%d8%a7%d8%a9-%d9%88%d9%85%d8%b4%d8%b7-%d8%a8%d8%b1%d8%aa%d9%82%d8%a7%d9%84%d9%8a\\\/\",\"url\":\"https:\\\/\\\/ozeyhome.com\\\/ar\\\/product\\\/%d8%b4%d9%8a%d9%83%d9%88-%d9%81%d8%b1%d8%b4%d8%a7%d8%a9-%d9%88%d9%85%d8%b4%d8%b7-%d8%a8%d8%b1%d8%aa%d9%82%d8%a7%d9%84%d9%8a\\\/\",\"name\":\"\u0641\u0631\u0634\u0627\u0629 \u0648\u0645\u0634\u0637 \u0628\u0631\u062a\u0642\u0627\u0644\u064a - \u062a\u0634\u064a\u0643\u0648 - Ozey Home\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ozeyhome.com\\\/ar\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ozeyhome.com\\\/ar\\\/product\\\/%d8%b4%d9%8a%d9%83%d9%88-%d9%81%d8%b1%d8%b4%d8%a7%d8%a9-%d9%88%d9%85%d8%b4%d8%b7-%d8%a8%d8%b1%d8%aa%d9%82%d8%a7%d9%84%d9%8a\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ozeyhome.com\\\/ar\\\/product\\\/%d8%b4%d9%8a%d9%83%d9%88-%d9%81%d8%b1%d8%b4%d8%a7%d8%a9-%d9%88%d9%85%d8%b4%d8%b7-%d8%a8%d8%b1%d8%aa%d9%82%d8%a7%d9%84%d9%8a\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ozeyhome.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/o3.png\",\"datePublished\":\"2023-08-09T16:20:43+00:00\",\"dateModified\":\"2026-06-20T09:39:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ozeyhome.com\\\/ar\\\/product\\\/%d8%b4%d9%8a%d9%83%d9%88-%d9%81%d8%b1%d8%b4%d8%a7%d8%a9-%d9%88%d9%85%d8%b4%d8%b7-%d8%a8%d8%b1%d8%aa%d9%82%d8%a7%d9%84%d9%8a\\\/#breadcrumb\"},\"inLanguage\":\"ar\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ozeyhome.com\\\/ar\\\/product\\\/%d8%b4%d9%8a%d9%83%d9%88-%d9%81%d8%b1%d8%b4%d8%a7%d8%a9-%d9%88%d9%85%d8%b4%d8%b7-%d8%a8%d8%b1%d8%aa%d9%82%d8%a7%d9%84%d9%8a\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ar\",\"@id\":\"https:\\\/\\\/ozeyhome.com\\\/ar\\\/product\\\/%d8%b4%d9%8a%d9%83%d9%88-%d9%81%d8%b1%d8%b4%d8%a7%d8%a9-%d9%88%d9%85%d8%b4%d8%b7-%d8%a8%d8%b1%d8%aa%d9%82%d8%a7%d9%84%d9%8a\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ozeyhome.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/o3.png\",\"contentUrl\":\"https:\\\/\\\/ozeyhome.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/o3.png\",\"width\":850,\"height\":850},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ozeyhome.com\\\/ar\\\/product\\\/%d8%b4%d9%8a%d9%83%d9%88-%d9%81%d8%b1%d8%b4%d8%a7%d8%a9-%d9%88%d9%85%d8%b4%d8%b7-%d8%a8%d8%b1%d8%aa%d9%82%d8%a7%d9%84%d9%8a\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ozeyhome.com\\\/ar\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/ozeyhome.com\\\/ar\\\/shop-2\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u0641\u0631\u0634\u0627\u0629 \u0648\u0645\u0634\u0637 \u0628\u0631\u062a\u0642\u0627\u0644\u064a &#8211; \u062a\u0634\u064a\u0643\u0648\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ozeyhome.com\\\/ar\\\/#website\",\"url\":\"https:\\\/\\\/ozeyhome.com\\\/ar\\\/\",\"name\":\"Ozey Home\",\"description\":\"Ozey Home Website\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ozeyhome.com\\\/ar\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ar\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0641\u0631\u0634\u0627\u0629 \u0648\u0645\u0634\u0637 \u0628\u0631\u062a\u0642\u0627\u0644\u064a - \u062a\u0634\u064a\u0643\u0648 - Ozey Home","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ozeyhome.com\/ar\/product\/%d8%b4%d9%8a%d9%83%d9%88-%d9%81%d8%b1%d8%b4%d8%a7%d8%a9-%d9%88%d9%85%d8%b4%d8%b7-%d8%a8%d8%b1%d8%aa%d9%82%d8%a7%d9%84%d9%8a\/","og_locale":"ar_AR","og_type":"article","og_title":"\u0641\u0631\u0634\u0627\u0629 \u0648\u0645\u0634\u0637 \u0628\u0631\u062a\u0642\u0627\u0644\u064a - \u062a\u0634\u064a\u0643\u0648 - Ozey Home","og_description":"\u0645\u0648\u0635\u0649 \u0628\u0647 \u0644\u0644\u0623\u0637\u0641\u0627\u0644 0M +. \u062a\u0639\u062a\u0628\u0631 \u0641\u0631\u0634\u0627\u0629 \u0648\u0645\u0634\u0637 \u0634\u064a\u0643\u0648 \u0645\u062b\u0627\u0644\u064a\u064a\u0646 \u0644\u062a\u0645\u0634\u064a\u0637 \u0634\u0639\u0631 \u0627\u0644\u0637\u0641\u0644 \u0628\u0623\u0642\u0635\u0649 \u062f\u0631\u062c\u0627\u062a \u0627\u0644\u062d\u0633\u0627\u0633\u064a\u0629. \u0647\u0630\u0647 \u0644\u0627 \u062a\u0624\u0630\u064a \u0627\u0644\u0637\u0641\u0644 \u0648\u0647\u064a \u0646\u0627\u0639\u0645\u0629 \u0644\u0634\u0639\u0631\u0647 \u0627\u0644\u0631\u0642\u064a\u0642 \u0648\u0641\u0631\u0648\u0629 \u0631\u0623\u0633\u0647. \u0627\u0644\u0639\u0645\u0631 \u0627\u0644\u0645\u0646\u0627\u0633\u0628: 0 \u0634\u0647\u0631 + \u0633\u0645\u0627\u062a \u0645\u0642\u0628\u0636 \u063a\u064a\u0631 \u0642\u0627\u0628\u0644 \u0644\u0644\u0627\u0646\u0632\u0644\u0627\u0642 \u0645\u0642\u0628\u0636 \u0639\u0631\u064a\u0636 \u0648\u063a\u064a\u0631 \u0642\u0627\u0628\u0644 \u0644\u0644\u0627\u0646\u0632\u0644\u0627\u0642 \u064a\u0633\u0645\u062d \u0628\u0642\u0628\u0636\u0629 \u0633\u0647\u0644\u0629 \u0648\u0622\u0645\u0646\u0629. \u0641\u0631\u0634\u0627\u0629 \u0628\u0634\u0639\u064a\u0631\u0627\u062a \u0637\u0628\u064a\u0639\u064a\u0629 \u062a\u062d\u062a\u0631\u0645 \u0627\u0644\u0634\u0639\u064a\u0631\u0627\u062a \u0627\u0644\u0637\u0628\u064a\u0639\u064a\u0629 \u0627\u0644\u0646\u0627\u0639\u0645\u0629 \u0644\u0641\u0631\u0634\u0627\u0629 \u0627\u0644\u0634\u0639\u0631 \u0634\u064a\u0643\u0648 &hellip; Continue reading \u0641\u0631\u0634\u0627\u0629 \u0648\u0645\u0634\u0637 \u0628\u0631\u062a\u0642\u0627\u0644\u064a &#8211; \u062a\u0634\u064a\u0643\u0648","og_url":"https:\/\/ozeyhome.com\/ar\/product\/%d8%b4%d9%8a%d9%83%d9%88-%d9%81%d8%b1%d8%b4%d8%a7%d8%a9-%d9%88%d9%85%d8%b4%d8%b7-%d8%a8%d8%b1%d8%aa%d9%82%d8%a7%d9%84%d9%8a\/","og_site_name":"Ozey Home","article_modified_time":"2026-06-20T09:39:37+00:00","og_image":[{"width":850,"height":850,"url":"https:\/\/ozeyhome.com\/wp-content\/uploads\/2023\/08\/o3.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"\u0648\u0642\u062a \u0627\u0644\u0642\u0631\u0627\u0621\u0629 \u0627\u0644\u0645\u064f\u0642\u062f\u0651\u0631":"\u062f\u0642\u064a\u0642\u062a\u0627\u0646"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ozeyhome.com\/ar\/product\/%d8%b4%d9%8a%d9%83%d9%88-%d9%81%d8%b1%d8%b4%d8%a7%d8%a9-%d9%88%d9%85%d8%b4%d8%b7-%d8%a8%d8%b1%d8%aa%d9%82%d8%a7%d9%84%d9%8a\/","url":"https:\/\/ozeyhome.com\/ar\/product\/%d8%b4%d9%8a%d9%83%d9%88-%d9%81%d8%b1%d8%b4%d8%a7%d8%a9-%d9%88%d9%85%d8%b4%d8%b7-%d8%a8%d8%b1%d8%aa%d9%82%d8%a7%d9%84%d9%8a\/","name":"\u0641\u0631\u0634\u0627\u0629 \u0648\u0645\u0634\u0637 \u0628\u0631\u062a\u0642\u0627\u0644\u064a - \u062a\u0634\u064a\u0643\u0648 - Ozey Home","isPartOf":{"@id":"https:\/\/ozeyhome.com\/ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ozeyhome.com\/ar\/product\/%d8%b4%d9%8a%d9%83%d9%88-%d9%81%d8%b1%d8%b4%d8%a7%d8%a9-%d9%88%d9%85%d8%b4%d8%b7-%d8%a8%d8%b1%d8%aa%d9%82%d8%a7%d9%84%d9%8a\/#primaryimage"},"image":{"@id":"https:\/\/ozeyhome.com\/ar\/product\/%d8%b4%d9%8a%d9%83%d9%88-%d9%81%d8%b1%d8%b4%d8%a7%d8%a9-%d9%88%d9%85%d8%b4%d8%b7-%d8%a8%d8%b1%d8%aa%d9%82%d8%a7%d9%84%d9%8a\/#primaryimage"},"thumbnailUrl":"https:\/\/ozeyhome.com\/wp-content\/uploads\/2023\/08\/o3.png","datePublished":"2023-08-09T16:20:43+00:00","dateModified":"2026-06-20T09:39:37+00:00","breadcrumb":{"@id":"https:\/\/ozeyhome.com\/ar\/product\/%d8%b4%d9%8a%d9%83%d9%88-%d9%81%d8%b1%d8%b4%d8%a7%d8%a9-%d9%88%d9%85%d8%b4%d8%b7-%d8%a8%d8%b1%d8%aa%d9%82%d8%a7%d9%84%d9%8a\/#breadcrumb"},"inLanguage":"ar","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ozeyhome.com\/ar\/product\/%d8%b4%d9%8a%d9%83%d9%88-%d9%81%d8%b1%d8%b4%d8%a7%d8%a9-%d9%88%d9%85%d8%b4%d8%b7-%d8%a8%d8%b1%d8%aa%d9%82%d8%a7%d9%84%d9%8a\/"]}]},{"@type":"ImageObject","inLanguage":"ar","@id":"https:\/\/ozeyhome.com\/ar\/product\/%d8%b4%d9%8a%d9%83%d9%88-%d9%81%d8%b1%d8%b4%d8%a7%d8%a9-%d9%88%d9%85%d8%b4%d8%b7-%d8%a8%d8%b1%d8%aa%d9%82%d8%a7%d9%84%d9%8a\/#primaryimage","url":"https:\/\/ozeyhome.com\/wp-content\/uploads\/2023\/08\/o3.png","contentUrl":"https:\/\/ozeyhome.com\/wp-content\/uploads\/2023\/08\/o3.png","width":850,"height":850},{"@type":"BreadcrumbList","@id":"https:\/\/ozeyhome.com\/ar\/product\/%d8%b4%d9%8a%d9%83%d9%88-%d9%81%d8%b1%d8%b4%d8%a7%d8%a9-%d9%88%d9%85%d8%b4%d8%b7-%d8%a8%d8%b1%d8%aa%d9%82%d8%a7%d9%84%d9%8a\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ozeyhome.com\/ar\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/ozeyhome.com\/ar\/shop-2\/"},{"@type":"ListItem","position":3,"name":"\u0641\u0631\u0634\u0627\u0629 \u0648\u0645\u0634\u0637 \u0628\u0631\u062a\u0642\u0627\u0644\u064a &#8211; \u062a\u0634\u064a\u0643\u0648"}]},{"@type":"WebSite","@id":"https:\/\/ozeyhome.com\/ar\/#website","url":"https:\/\/ozeyhome.com\/ar\/","name":"Ozey Home","description":"Ozey Home Website","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ozeyhome.com\/ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ar"}]}},"_links":{"self":[{"href":"https:\/\/ozeyhome.com\/ar\/wp-json\/wp\/v2\/product\/26071","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ozeyhome.com\/ar\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/ozeyhome.com\/ar\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":0,"href":"https:\/\/ozeyhome.com\/ar\/wp-json\/wp\/v2\/product\/26071\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ozeyhome.com\/ar\/wp-json\/wp\/v2\/media\/25717"}],"wp:attachment":[{"href":"https:\/\/ozeyhome.com\/ar\/wp-json\/wp\/v2\/media?parent=26071"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/ozeyhome.com\/ar\/wp-json\/wp\/v2\/product_brand?post=26071"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/ozeyhome.com\/ar\/wp-json\/wp\/v2\/product_cat?post=26071"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/ozeyhome.com\/ar\/wp-json\/wp\/v2\/product_tag?post=26071"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}